{"id":1108,"count":0,"description":"","link":"https:\/\/beneixama.diputacionalicante.es\/ca\/category\/noticies\/ministerio-de-igualdad-2\/","name":"Ministerio de Igualdad","slug":"ministerio-de-igualdad-2","taxonomy":"category","parent":1095,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ministerio de Igualdad archivos &#062; Ayuntamiento de Beneixama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beneixama.diputacionalicante.es\/ca\/category\/noticies\/ministerio-de-igualdad-2\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ministerio de Igualdad archivos &#062; Ayuntamiento de Beneixama\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beneixama.diputacionalicante.es\/ca\/category\/noticies\/ministerio-de-igualdad-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ayuntamiento de Beneixama\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/D006263.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"2025\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/category\/noticies\/ministerio-de-igualdad-2\/\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/category\/noticies\/ministerio-de-igualdad-2\/\",\"name\":\"Ministerio de Igualdad archivos &#062; Ayuntamiento de Beneixama\",\"isPartOf\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/category\/noticies\/ministerio-de-igualdad-2\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/category\/noticies\/ministerio-de-igualdad-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ministerio de Igualdad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#website\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\",\"name\":\"Ayuntamiento de Beneixama\",\"description\":\"Ayuntamiento de Beneixama\",\"publisher\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization\"},\"alternateName\":\"Ayuntamiento de Beneixama\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization\",\"name\":\"Ayuntamiento de Beneixama\",\"alternateName\":\"Ayuntamiento de Beneixama\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png\",\"contentUrl\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png\",\"width\":350,\"height\":150,\"caption\":\"Ayuntamiento de Beneixama\"},\"image\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ministerio de Igualdad archivos &#062; Ayuntamiento de Beneixama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beneixama.diputacionalicante.es\/ca\/category\/noticies\/ministerio-de-igualdad-2\/","og_locale":"ca_ES","og_type":"article","og_title":"Ministerio de Igualdad archivos &#062; Ayuntamiento de Beneixama","og_url":"https:\/\/beneixama.diputacionalicante.es\/ca\/category\/noticies\/ministerio-de-igualdad-2\/","og_site_name":"Ayuntamiento de Beneixama","og_image":[{"width":2048,"height":2025,"url":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/D006263.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/category\/noticies\/ministerio-de-igualdad-2\/","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/category\/noticies\/ministerio-de-igualdad-2\/","name":"Ministerio de Igualdad archivos &#062; Ayuntamiento de Beneixama","isPartOf":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#website"},"breadcrumb":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/category\/noticies\/ministerio-de-igualdad-2\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/category\/noticies\/ministerio-de-igualdad-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/beneixama.diputacionalicante.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Ministerio de Igualdad"}]},{"@type":"WebSite","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#website","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/","name":"Ayuntamiento de Beneixama","description":"Ayuntamiento de Beneixama","publisher":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization"},"alternateName":"Ayuntamiento de Beneixama","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beneixama.diputacionalicante.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization","name":"Ayuntamiento de Beneixama","alternateName":"Ayuntamiento de Beneixama","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png","contentUrl":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png","width":350,"height":150,"caption":"Ayuntamiento de Beneixama"},"image":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/categories\/1108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/categories\/1095"}],"wp:post_type":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/posts?categories=1108"},{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/pages?categories=1108"},{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/comercio_local?categories=1108"},{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/procesos_selectivos?categories=1108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}