{"id":32782,"date":"2024-04-25T06:33:01","date_gmt":"2024-04-25T04:33:01","guid":{"rendered":"https:\/\/beneixama.diputacionalicante.es\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/"},"modified":"2025-06-17T11:18:52","modified_gmt":"2025-06-17T09:18:52","slug":"consulta-popular-data-de-les-festes-de-moros-i-cristians","status":"publish","type":"post","link":"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/","title":{"rendered":"CONSULTA POPULAR -DATA DE LES FESTES DE MOROS I CRISTIANS-."},"content":{"rendered":"<p>El 22 de juny de 2024 es dur\u00e0 a terme una consulta popular per a con\u00e8ixer l&#8217;opini\u00f3 de totes les persones involucrades en les nostres Festes de Moros i Cristians.\u00a0\u00c9s molt important la participaci\u00f3 de tothom per a saber quina \u00e9s l&#8217;opini\u00f3 majorit\u00e0ria i actuar aix\u00ed amb determinaci\u00f3, per aix\u00f2 vos animem a totes i tots a votar i expresar el vostre parer.<\/p>\n<p>Ac\u00ed teniu un recull de la informaci\u00f3 m\u00e9s important a l&#8217;hora d&#8217;exercir el vot.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-41731 size-full\" src=\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/1_instagram_tot_consulta.jpg\" alt=\" width=\"1080\" height=\"1080\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 22 de juny de 2024 es dur\u00e0 a terme una consulta popular per a con\u00e8ixer l&#8217;opini\u00f3 de totes les &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"CONSULTA POPULAR -DATA DE LES FESTES DE MOROS I CRISTIANS-.\" class=\"read-more button\" href=\"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/#more-32782\" aria-label=\"M\u00e9s informaci\u00f3 sobre CONSULTA POPULAR -DATA DE LES FESTES DE MOROS I CRISTIANS-.\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":31052,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1095],"tags":[537,526,540,575,576,577,578,566,579,580,549],"class_list":["post-32782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies","tag-2024-2","tag-ajuntamentdebeneixama-2","tag-beneixama-2","tag-censo-2","tag-consultapopular-2","tag-datafestes","tag-morosicristians-2","tag-regidoriadefestes","tag-vot","tag-canvifestes","tag-festes-2","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","resize-featured-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONSULTA POPULAR -DATA DE LES FESTES DE MOROS I CRISTIANS-. &#062; Ayuntamiento de Beneixama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONSULTA POPULAR -DATA DE LES FESTES DE MOROS I CRISTIANS-. &#062; Ayuntamiento de Beneixama\" \/>\n<meta property=\"og:description\" content=\"El 22 de juny de 2024 es dur\u00e0 a terme una consulta popular per a con\u00e8ixer l&#8217;opini\u00f3 de totes les ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/\" \/>\n<meta property=\"og:site_name\" content=\"Ayuntamiento de Beneixama\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-25T04:33:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-17T09:18:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/1_instagram_tot_consulta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"externo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"externo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/\"},\"author\":{\"name\":\"externo\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/a50bb4b71ed78f36f3dea9d6e18279fc\"},\"headline\":\"CONSULTA POPULAR -DATA DE LES FESTES DE MOROS I CRISTIANS-.\",\"datePublished\":\"2024-04-25T04:33:01+00:00\",\"dateModified\":\"2025-06-17T09:18:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/\"},\"wordCount\":93,\"publisher\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization\"},\"image\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/1_instagram_tot_consulta.jpg\",\"keywords\":[\"#2024\",\"#AjuntamentdeBeneixama\",\"#beneixama\",\"#censo\",\"#consultapopular\",\"#datafestes\",\"#morosicristians\",\"#regidoriadefestes\",\"#vot\",\"canvifestes\",\"festes\"],\"articleSection\":[\"Not\u00edcies\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/\",\"name\":\"CONSULTA POPULAR -DATA DE LES FESTES DE MOROS I CRISTIANS-. &#062; Ayuntamiento de Beneixama\",\"isPartOf\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/1_instagram_tot_consulta.jpg\",\"datePublished\":\"2024-04-25T04:33:01+00:00\",\"dateModified\":\"2025-06-17T09:18:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/#primaryimage\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/1_instagram_tot_consulta.jpg\",\"contentUrl\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/1_instagram_tot_consulta.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONSULTA POPULAR -DATA DE LES FESTES DE MOROS I CRISTIANS-.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#website\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\",\"name\":\"Ayuntamiento de Beneixama\",\"description\":\"Ayuntamiento de Beneixama\",\"publisher\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization\"},\"alternateName\":\"Ayuntamiento de Beneixama\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization\",\"name\":\"Ayuntamiento de Beneixama\",\"alternateName\":\"Ayuntamiento de Beneixama\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png\",\"contentUrl\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png\",\"width\":350,\"height\":150,\"caption\":\"Ayuntamiento de Beneixama\"},\"image\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/a50bb4b71ed78f36f3dea9d6e18279fc\",\"name\":\"externo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5c855e7021b20651668f552333c77bfb05313b8dabc0baa084eedff5b9b95920?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5c855e7021b20651668f552333c77bfb05313b8dabc0baa084eedff5b9b95920?s=96&d=mm&r=g\",\"caption\":\"externo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONSULTA POPULAR -DATA DE LES FESTES DE MOROS I CRISTIANS-. &#062; Ayuntamiento de Beneixama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/","og_locale":"ca_ES","og_type":"article","og_title":"CONSULTA POPULAR -DATA DE LES FESTES DE MOROS I CRISTIANS-. &#062; Ayuntamiento de Beneixama","og_description":"El 22 de juny de 2024 es dur\u00e0 a terme una consulta popular per a con\u00e8ixer l&#8217;opini\u00f3 de totes les ... Read more","og_url":"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/","og_site_name":"Ayuntamiento de Beneixama","article_published_time":"2024-04-25T04:33:01+00:00","article_modified_time":"2025-06-17T09:18:52+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/1_instagram_tot_consulta.jpg","type":"image\/jpeg"}],"author":"externo","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"externo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/#article","isPartOf":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/"},"author":{"name":"externo","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/a50bb4b71ed78f36f3dea9d6e18279fc"},"headline":"CONSULTA POPULAR -DATA DE LES FESTES DE MOROS I CRISTIANS-.","datePublished":"2024-04-25T04:33:01+00:00","dateModified":"2025-06-17T09:18:52+00:00","mainEntityOfPage":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/"},"wordCount":93,"publisher":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization"},"image":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/#primaryimage"},"thumbnailUrl":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/1_instagram_tot_consulta.jpg","keywords":["#2024","#AjuntamentdeBeneixama","#beneixama","#censo","#consultapopular","#datafestes","#morosicristians","#regidoriadefestes","#vot","canvifestes","festes"],"articleSection":["Not\u00edcies"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/","name":"CONSULTA POPULAR -DATA DE LES FESTES DE MOROS I CRISTIANS-. &#062; Ayuntamiento de Beneixama","isPartOf":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/#primaryimage"},"image":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/#primaryimage"},"thumbnailUrl":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/1_instagram_tot_consulta.jpg","datePublished":"2024-04-25T04:33:01+00:00","dateModified":"2025-06-17T09:18:52+00:00","breadcrumb":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/#primaryimage","url":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/1_instagram_tot_consulta.jpg","contentUrl":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/1_instagram_tot_consulta.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/consulta-popular-data-de-les-festes-de-moros-i-cristians\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/beneixama.diputacionalicante.es\/ca\/"},{"@type":"ListItem","position":2,"name":"CONSULTA POPULAR -DATA DE LES FESTES DE MOROS I CRISTIANS-."}]},{"@type":"WebSite","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#website","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/","name":"Ayuntamiento de Beneixama","description":"Ayuntamiento de Beneixama","publisher":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization"},"alternateName":"Ayuntamiento de Beneixama","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beneixama.diputacionalicante.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization","name":"Ayuntamiento de Beneixama","alternateName":"Ayuntamiento de Beneixama","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png","contentUrl":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png","width":350,"height":150,"caption":"Ayuntamiento de Beneixama"},"image":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/a50bb4b71ed78f36f3dea9d6e18279fc","name":"externo","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5c855e7021b20651668f552333c77bfb05313b8dabc0baa084eedff5b9b95920?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c855e7021b20651668f552333c77bfb05313b8dabc0baa084eedff5b9b95920?s=96&d=mm&r=g","caption":"externo"}}]}},"_links":{"self":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/posts\/32782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/comments?post=32782"}],"version-history":[{"count":1,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/posts\/32782\/revisions"}],"predecessor-version":[{"id":32783,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/posts\/32782\/revisions\/32783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/media\/31052"}],"wp:attachment":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/media?parent=32782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/categories?post=32782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/tags?post=32782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}