{"id":32941,"date":"2024-07-01T10:07:21","date_gmt":"2024-07-01T08:07:21","guid":{"rendered":"https:\/\/beneixama.diputacionalicante.es\/concert-destiu-s-m-la-pau-de-beneixama-2\/"},"modified":"2025-06-17T11:19:38","modified_gmt":"2025-06-17T09:19:38","slug":"concert-destiu-s-m-la-pau-de-beneixama-2","status":"publish","type":"post","link":"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/","title":{"rendered":"CONCERT D&#8217;ESTIU -S.M LA PAU DE BENEIXAMA-"},"content":{"rendered":"<p>Dissabte 6 de juliol a les 23:00 hores davant de l&#8217;Ajuntament.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-42638\" src=\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/new_york-214x300.jpeg\" alt=\" width=\"214\" height=\"300\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dissabte 6 de juliol a les 23:00 hores davant de l&#8217;Ajuntament.<\/p>\n","protected":false},"author":2,"featured_media":31540,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1098,1097,1099,1095],"tags":[537,810,811],"class_list":["post-32941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-21-beneixarxa-2","category-beneixarxa-2","category-esdeveniments-anuncis","category-noticies","tag-2024-2","tag-concertdestiu-2","tag-lapaudebeneixama-2","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","resize-featured-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONCERT D&#039;ESTIU -S.M LA PAU DE BENEIXAMA- &#062; Ayuntamiento de Beneixama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONCERT D&#039;ESTIU -S.M LA PAU DE BENEIXAMA- &#062; Ayuntamiento de Beneixama\" \/>\n<meta property=\"og:description\" content=\"Dissabte 6 de juliol a les 23:00 hores davant de l&#8217;Ajuntament.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ayuntamiento de Beneixama\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-01T08:07:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-17T09:19:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/new_york.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1139\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"externo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"externo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/\"},\"author\":{\"name\":\"externo\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/a50bb4b71ed78f36f3dea9d6e18279fc\"},\"headline\":\"CONCERT D&#8217;ESTIU -S.M LA PAU DE BENEIXAMA-\",\"datePublished\":\"2024-07-01T08:07:21+00:00\",\"dateModified\":\"2025-06-17T09:19:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/\"},\"wordCount\":19,\"publisher\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization\"},\"image\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/new_york.jpeg\",\"keywords\":[\"#2024\",\"#concertd'estiu\",\"#lapaudebeneixama,\"],\"articleSection\":[\"Agenda 21\",\"Beneixarxa\",\"Esdeveniments \/ Anuncis\",\"Not\u00edcies\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/\",\"name\":\"CONCERT D'ESTIU -S.M LA PAU DE BENEIXAMA- &#062; Ayuntamiento de Beneixama\",\"isPartOf\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/new_york.jpeg\",\"datePublished\":\"2024-07-01T08:07:21+00:00\",\"dateModified\":\"2025-06-17T09:19:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/#primaryimage\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/new_york.jpeg\",\"contentUrl\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/new_york.jpeg\",\"width\":1139,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONCERT D&#8217;ESTIU -S.M LA PAU DE BENEIXAMA-\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#website\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\",\"name\":\"Ayuntamiento de Beneixama\",\"description\":\"Ayuntamiento de Beneixama\",\"publisher\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization\"},\"alternateName\":\"Ayuntamiento de Beneixama\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization\",\"name\":\"Ayuntamiento de Beneixama\",\"alternateName\":\"Ayuntamiento de Beneixama\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png\",\"contentUrl\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png\",\"width\":350,\"height\":150,\"caption\":\"Ayuntamiento de Beneixama\"},\"image\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/a50bb4b71ed78f36f3dea9d6e18279fc\",\"name\":\"externo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5c855e7021b20651668f552333c77bfb05313b8dabc0baa084eedff5b9b95920?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5c855e7021b20651668f552333c77bfb05313b8dabc0baa084eedff5b9b95920?s=96&d=mm&r=g\",\"caption\":\"externo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONCERT D'ESTIU -S.M LA PAU DE BENEIXAMA- &#062; Ayuntamiento de Beneixama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/","og_locale":"ca_ES","og_type":"article","og_title":"CONCERT D'ESTIU -S.M LA PAU DE BENEIXAMA- &#062; Ayuntamiento de Beneixama","og_description":"Dissabte 6 de juliol a les 23:00 hores davant de l&#8217;Ajuntament.","og_url":"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/","og_site_name":"Ayuntamiento de Beneixama","article_published_time":"2024-07-01T08:07:21+00:00","article_modified_time":"2025-06-17T09:19:38+00:00","og_image":[{"width":1139,"height":1600,"url":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/new_york.jpeg","type":"image\/jpeg"}],"author":"externo","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"externo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/#article","isPartOf":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/"},"author":{"name":"externo","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/a50bb4b71ed78f36f3dea9d6e18279fc"},"headline":"CONCERT D&#8217;ESTIU -S.M LA PAU DE BENEIXAMA-","datePublished":"2024-07-01T08:07:21+00:00","dateModified":"2025-06-17T09:19:38+00:00","mainEntityOfPage":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/"},"wordCount":19,"publisher":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization"},"image":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/#primaryimage"},"thumbnailUrl":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/new_york.jpeg","keywords":["#2024","#concertd'estiu","#lapaudebeneixama,"],"articleSection":["Agenda 21","Beneixarxa","Esdeveniments \/ Anuncis","Not\u00edcies"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/","name":"CONCERT D'ESTIU -S.M LA PAU DE BENEIXAMA- &#062; Ayuntamiento de Beneixama","isPartOf":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/#primaryimage"},"image":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/#primaryimage"},"thumbnailUrl":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/new_york.jpeg","datePublished":"2024-07-01T08:07:21+00:00","dateModified":"2025-06-17T09:19:38+00:00","breadcrumb":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/#primaryimage","url":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/new_york.jpeg","contentUrl":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/new_york.jpeg","width":1139,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/concert-destiu-s-m-la-pau-de-beneixama-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/beneixama.diputacionalicante.es\/ca\/"},{"@type":"ListItem","position":2,"name":"CONCERT D&#8217;ESTIU -S.M LA PAU DE BENEIXAMA-"}]},{"@type":"WebSite","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#website","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/","name":"Ayuntamiento de Beneixama","description":"Ayuntamiento de Beneixama","publisher":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization"},"alternateName":"Ayuntamiento de Beneixama","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beneixama.diputacionalicante.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization","name":"Ayuntamiento de Beneixama","alternateName":"Ayuntamiento de Beneixama","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png","contentUrl":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png","width":350,"height":150,"caption":"Ayuntamiento de Beneixama"},"image":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/a50bb4b71ed78f36f3dea9d6e18279fc","name":"externo","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5c855e7021b20651668f552333c77bfb05313b8dabc0baa084eedff5b9b95920?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c855e7021b20651668f552333c77bfb05313b8dabc0baa084eedff5b9b95920?s=96&d=mm&r=g","caption":"externo"}}]}},"_links":{"self":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/posts\/32941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/comments?post=32941"}],"version-history":[{"count":1,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/posts\/32941\/revisions"}],"predecessor-version":[{"id":32942,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/posts\/32941\/revisions\/32942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/media\/31540"}],"wp:attachment":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/media?parent=32941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/categories?post=32941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/tags?post=32941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}