{"id":32975,"date":"2024-07-12T10:03:59","date_gmt":"2024-07-12T08:03:59","guid":{"rendered":"https:\/\/beneixama.diputacionalicante.es\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/"},"modified":"2025-06-17T11:19:46","modified_gmt":"2025-06-17T09:19:46","slug":"resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024","status":"publish","type":"post","link":"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/","title":{"rendered":"Resoluci\u00f3 de subv. a favor Ajuntaments i EELL Prov.Alacant amb poblaci\u00f3 fins a 20.000 hab., per a realitzaci\u00f3 inversions camins tit. mncpal. anualitat 2024"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.beneixama.es\/wp-content\/uploads\/2024\/07\/Resolucion_concesion_inversion_caminos.pdf\">Resoluci\u00f3_concesi\u00f3_inversi\u00f3_camins<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-42807 size-large\" src=\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/Publicacio_concessio_subvencio-1-1-723x1024.jpg\" alt=\" width=\"723\" height=\"1024\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Resoluci\u00f3_concesi\u00f3_inversi\u00f3_camins<\/p>\n","protected":false},"author":2,"featured_media":31025,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1098,1097,1096,1099,1095,1100],"tags":[537,553,854,855,555,856,535],"class_list":["post-32975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-21-beneixarxa-2","category-beneixarxa-2","category-destacat","category-esdeveniments-anuncis","category-noticies","category-uncategorized-ca","tag-2024-2","tag-ajuntamentbeneixama-2","tag-camimolinet","tag-camins","tag-diputacioalacant","tag-titularitatmunicipal","tag-subvencions-2","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","resize-featured-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resoluci\u00f3 de subv. a favor Ajuntaments i EELL Prov.Alacant amb poblaci\u00f3 fins a 20.000 hab., per a realitzaci\u00f3 inversions camins tit. mncpal. anualitat 2024 &#062; Ayuntamiento de Beneixama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resoluci\u00f3 de subv. a favor Ajuntaments i EELL Prov.Alacant amb poblaci\u00f3 fins a 20.000 hab., per a realitzaci\u00f3 inversions camins tit. mncpal. anualitat 2024 &#062; Ayuntamiento de Beneixama\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Resoluci\u00f3_concesi\u00f3_inversi\u00f3_camins\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Ayuntamiento de Beneixama\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-12T08:03:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-17T09:19:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/imagen_logo_dipu.png\" \/>\n\t<meta property=\"og:image:width\" content=\"117\" \/>\n\t<meta property=\"og:image:height\" content=\"130\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"externo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"externo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/\"},\"author\":{\"name\":\"externo\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/a50bb4b71ed78f36f3dea9d6e18279fc\"},\"headline\":\"Resoluci\u00f3 de subv. a favor Ajuntaments i EELL Prov.Alacant amb poblaci\u00f3 fins a 20.000 hab., per a realitzaci\u00f3 inversions camins tit. mncpal. anualitat 2024\",\"datePublished\":\"2024-07-12T08:03:59+00:00\",\"dateModified\":\"2025-06-17T09:19:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/\"},\"wordCount\":28,\"publisher\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization\"},\"image\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/imagen_logo_dipu.png\",\"keywords\":[\"#2024\",\"#AjuntamentBeneixama\",\"#cam\u00edmolinet\",\"#camins\",\"#Diputaci\u00f3Alacant\",\"#titularitatmunicipal\",\"subvencions\"],\"articleSection\":[\"Agenda 21\",\"Beneixarxa\",\"Destacat\",\"Esdeveniments \/ Anuncis\",\"Not\u00edcies\",\"Sense Categoria\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/\",\"name\":\"Resoluci\u00f3 de subv. a favor Ajuntaments i EELL Prov.Alacant amb poblaci\u00f3 fins a 20.000 hab., per a realitzaci\u00f3 inversions camins tit. mncpal. anualitat 2024 &#062; Ayuntamiento de Beneixama\",\"isPartOf\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/imagen_logo_dipu.png\",\"datePublished\":\"2024-07-12T08:03:59+00:00\",\"dateModified\":\"2025-06-17T09:19:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/#primaryimage\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/imagen_logo_dipu.png\",\"contentUrl\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/imagen_logo_dipu.png\",\"width\":117,\"height\":130},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resoluci\u00f3 de subv. a favor Ajuntaments i EELL Prov.Alacant amb poblaci\u00f3 fins a 20.000 hab., per a realitzaci\u00f3 inversions camins tit. mncpal. anualitat 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#website\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\",\"name\":\"Ayuntamiento de Beneixama\",\"description\":\"Ayuntamiento de Beneixama\",\"publisher\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization\"},\"alternateName\":\"Ayuntamiento de Beneixama\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization\",\"name\":\"Ayuntamiento de Beneixama\",\"alternateName\":\"Ayuntamiento de Beneixama\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png\",\"contentUrl\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png\",\"width\":350,\"height\":150,\"caption\":\"Ayuntamiento de Beneixama\"},\"image\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/a50bb4b71ed78f36f3dea9d6e18279fc\",\"name\":\"externo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5c855e7021b20651668f552333c77bfb05313b8dabc0baa084eedff5b9b95920?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5c855e7021b20651668f552333c77bfb05313b8dabc0baa084eedff5b9b95920?s=96&d=mm&r=g\",\"caption\":\"externo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resoluci\u00f3 de subv. a favor Ajuntaments i EELL Prov.Alacant amb poblaci\u00f3 fins a 20.000 hab., per a realitzaci\u00f3 inversions camins tit. mncpal. anualitat 2024 &#062; Ayuntamiento de Beneixama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/","og_locale":"ca_ES","og_type":"article","og_title":"Resoluci\u00f3 de subv. a favor Ajuntaments i EELL Prov.Alacant amb poblaci\u00f3 fins a 20.000 hab., per a realitzaci\u00f3 inversions camins tit. mncpal. anualitat 2024 &#062; Ayuntamiento de Beneixama","og_description":"&nbsp; Resoluci\u00f3_concesi\u00f3_inversi\u00f3_camins","og_url":"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/","og_site_name":"Ayuntamiento de Beneixama","article_published_time":"2024-07-12T08:03:59+00:00","article_modified_time":"2025-06-17T09:19:46+00:00","og_image":[{"width":117,"height":130,"url":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/imagen_logo_dipu.png","type":"image\/png"}],"author":"externo","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"externo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/#article","isPartOf":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/"},"author":{"name":"externo","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/a50bb4b71ed78f36f3dea9d6e18279fc"},"headline":"Resoluci\u00f3 de subv. a favor Ajuntaments i EELL Prov.Alacant amb poblaci\u00f3 fins a 20.000 hab., per a realitzaci\u00f3 inversions camins tit. mncpal. anualitat 2024","datePublished":"2024-07-12T08:03:59+00:00","dateModified":"2025-06-17T09:19:46+00:00","mainEntityOfPage":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/"},"wordCount":28,"publisher":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization"},"image":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/imagen_logo_dipu.png","keywords":["#2024","#AjuntamentBeneixama","#cam\u00edmolinet","#camins","#Diputaci\u00f3Alacant","#titularitatmunicipal","subvencions"],"articleSection":["Agenda 21","Beneixarxa","Destacat","Esdeveniments \/ Anuncis","Not\u00edcies","Sense Categoria"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/","name":"Resoluci\u00f3 de subv. a favor Ajuntaments i EELL Prov.Alacant amb poblaci\u00f3 fins a 20.000 hab., per a realitzaci\u00f3 inversions camins tit. mncpal. anualitat 2024 &#062; Ayuntamiento de Beneixama","isPartOf":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/#primaryimage"},"image":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/imagen_logo_dipu.png","datePublished":"2024-07-12T08:03:59+00:00","dateModified":"2025-06-17T09:19:46+00:00","breadcrumb":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/#primaryimage","url":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/imagen_logo_dipu.png","contentUrl":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/06\/imagen_logo_dipu.png","width":117,"height":130},{"@type":"BreadcrumbList","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/resolucio-de-subv-a-favor-ajuntaments-i-eell-prov-alacant-amb-poblacio-fins-a-20-000-hab-per-a-realitzacio-inversions-camins-tit-mncpal-anualitat-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/beneixama.diputacionalicante.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Resoluci\u00f3 de subv. a favor Ajuntaments i EELL Prov.Alacant amb poblaci\u00f3 fins a 20.000 hab., per a realitzaci\u00f3 inversions camins tit. mncpal. anualitat 2024"}]},{"@type":"WebSite","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#website","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/","name":"Ayuntamiento de Beneixama","description":"Ayuntamiento de Beneixama","publisher":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization"},"alternateName":"Ayuntamiento de Beneixama","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beneixama.diputacionalicante.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization","name":"Ayuntamiento de Beneixama","alternateName":"Ayuntamiento de Beneixama","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png","contentUrl":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png","width":350,"height":150,"caption":"Ayuntamiento de Beneixama"},"image":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/a50bb4b71ed78f36f3dea9d6e18279fc","name":"externo","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5c855e7021b20651668f552333c77bfb05313b8dabc0baa084eedff5b9b95920?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c855e7021b20651668f552333c77bfb05313b8dabc0baa084eedff5b9b95920?s=96&d=mm&r=g","caption":"externo"}}]}},"_links":{"self":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/posts\/32975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/comments?post=32975"}],"version-history":[{"count":1,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/posts\/32975\/revisions"}],"predecessor-version":[{"id":32976,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/posts\/32975\/revisions\/32976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/media\/31025"}],"wp:attachment":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/media?parent=32975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/categories?post=32975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/tags?post=32975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}