{"id":34534,"date":"2018-12-10T09:33:37","date_gmt":"2018-12-10T08:33:37","guid":{"rendered":"https:\/\/beneixama.diputacionalicante.es\/event\/pastora\/"},"modified":"2018-12-10T09:33:37","modified_gmt":"2018-12-10T08:33:37","slug":"pastora","status":"publish","type":"tribe_events","link":"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/pastora\/","title":{"rendered":"Pastor\u00e0."},"content":{"rendered":"<p>El diumenge <strong>30 de desembre<\/strong>, a les <strong>12.00 hores<\/strong> en la <strong>porta de l&#8217;Esgl\u00e9sia<\/strong>, tindr\u00e0 lloc la tradicional <strong>Pastor\u00e0<\/strong>.<\/p>\n<p><strong>L&#8217;A.M.P.A. C.P: Divina Aurora agraeix que s&#8217;aporten productes de primera necessitat.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El diumenge 30 de desembre, a les 12.00 hores en la porta de l&#8217;Esgl\u00e9sia, tindr\u00e0 lloc la tradicional Pastor\u00e0. L&#8217;A.M.P.A. &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Pastor\u00e0.\" class=\"read-more button\" href=\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/pastora\/#more-34534\" aria-label=\"M\u00e9s informaci\u00f3 sobre Pastor\u00e0.\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[540,542],"tribe_events_cat":[1255,1238,1237,1236],"class_list":["post-34534","tribe_events","type-tribe_events","status-publish","hentry","tag-beneixama-2","tag-ajuntament-de-beneixama","tribe_events_cat-agenda-21","tribe_events_cat-ampa","tribe_events_cat-associacions","tribe_events_cat-beneixarxa","cat_agenda-21","cat_ampa","cat_associacions","cat_beneixarxa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pastor\u00e0. &#062; Ayuntamiento de Beneixama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/pastora\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pastor\u00e0. &#062; Ayuntamiento de Beneixama\" \/>\n<meta property=\"og:description\" content=\"El diumenge 30 de desembre, a les 12.00 hores en la porta de l&#8217;Esgl\u00e9sia, tindr\u00e0 lloc la tradicional Pastor\u00e0. L&#8217;A.M.P.A. ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/pastora\/\" \/>\n<meta property=\"og:site_name\" content=\"Ayuntamiento de Beneixama\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/D006263.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"2025\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/pastora\/\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/pastora\/\",\"name\":\"Pastor\u00e0. &#062; Ayuntamiento de Beneixama\",\"isPartOf\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#website\"},\"datePublished\":\"2018-12-10T08:33:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/pastora\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/pastora\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/pastora\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/events\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pastor\u00e0.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#website\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\",\"name\":\"Ayuntamiento de Beneixama\",\"description\":\"Ayuntamiento de Beneixama\",\"publisher\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization\"},\"alternateName\":\"Ayuntamiento de Beneixama\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization\",\"name\":\"Ayuntamiento de Beneixama\",\"alternateName\":\"Ayuntamiento de Beneixama\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png\",\"contentUrl\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png\",\"width\":350,\"height\":150,\"caption\":\"Ayuntamiento de Beneixama\"},\"image\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pastor\u00e0. &#062; Ayuntamiento de Beneixama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/pastora\/","og_locale":"ca_ES","og_type":"article","og_title":"Pastor\u00e0. &#062; Ayuntamiento de Beneixama","og_description":"El diumenge 30 de desembre, a les 12.00 hores en la porta de l&#8217;Esgl\u00e9sia, tindr\u00e0 lloc la tradicional Pastor\u00e0. L&#8217;A.M.P.A. ... Read more","og_url":"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/pastora\/","og_site_name":"Ayuntamiento de Beneixama","og_image":[{"width":2048,"height":2025,"url":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/D006263.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/pastora\/","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/pastora\/","name":"Pastor\u00e0. &#062; Ayuntamiento de Beneixama","isPartOf":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#website"},"datePublished":"2018-12-10T08:33:37+00:00","breadcrumb":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/pastora\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beneixama.diputacionalicante.es\/ca\/event\/pastora\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/pastora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/beneixama.diputacionalicante.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/beneixama.diputacionalicante.es\/ca\/events\/"},{"@type":"ListItem","position":3,"name":"Pastor\u00e0."}]},{"@type":"WebSite","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#website","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/","name":"Ayuntamiento de Beneixama","description":"Ayuntamiento de Beneixama","publisher":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization"},"alternateName":"Ayuntamiento de Beneixama","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beneixama.diputacionalicante.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization","name":"Ayuntamiento de Beneixama","alternateName":"Ayuntamiento de Beneixama","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png","contentUrl":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png","width":350,"height":150,"caption":"Ayuntamiento de Beneixama"},"image":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/tribe_events\/34534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/tribe_events\/34534\/revisions"}],"wp:attachment":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/media?parent=34534"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/tags?post=34534"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/tribe_events_cat?post=34534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}