{"id":34611,"date":"2019-06-18T09:47:42","date_gmt":"2019-06-18T07:47:42","guid":{"rendered":"https:\/\/beneixama.diputacionalicante.es\/event\/ecoparc-mobil\/"},"modified":"2025-09-11T13:18:53","modified_gmt":"2025-09-11T11:18:53","slug":"ecoparc-mobil","status":"publish","type":"tribe_events","link":"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/","title":{"rendered":"Ecoparc m\u00f2bil."},"content":{"rendered":"<p><a href=\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/09\/Cartel-General-Horarios-scaled.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-35073\" src=\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/09\/Cartel-General-Horarios-scaled.png\" alt=\" width=\"1920\" height=\"3927\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":33714,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[1255,1236,1266,1265],"class_list":["post-34611","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-agenda-21","tribe_events_cat-beneixarxa","tribe_events_cat-eficiencia-energetica","tribe_events_cat-medi-ambient","resize-featured-image","cat_agenda-21","cat_beneixarxa","cat_eficiencia-energetica","cat_medi-ambient"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecoparc m\u00f2bil. &#062; Ayuntamiento de Beneixama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecoparc m\u00f2bil. &#062; Ayuntamiento de Beneixama\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/\" \/>\n<meta property=\"og:site_name\" content=\"Ayuntamiento de Beneixama\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-11T11:18:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/09\/Cartel-General-Horarios-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1252\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/\",\"name\":\"Ecoparc m\u00f2bil. &#062; Ayuntamiento de Beneixama\",\"isPartOf\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/09\/Cartel-General-Horarios-scaled.png\",\"datePublished\":\"2019-06-18T07:47:42+00:00\",\"dateModified\":\"2025-09-11T11:18:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/#primaryimage\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/09\/Cartel-General-Horarios-scaled.png\",\"contentUrl\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/09\/Cartel-General-Horarios-scaled.png\",\"width\":1252,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/events\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ecoparc m\u00f2bil.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#website\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\",\"name\":\"Ayuntamiento de Beneixama\",\"description\":\"Ayuntamiento de Beneixama\",\"publisher\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization\"},\"alternateName\":\"Ayuntamiento de Beneixama\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization\",\"name\":\"Ayuntamiento de Beneixama\",\"alternateName\":\"Ayuntamiento de Beneixama\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png\",\"contentUrl\":\"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png\",\"width\":350,\"height\":150,\"caption\":\"Ayuntamiento de Beneixama\"},\"image\":{\"@id\":\"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecoparc m\u00f2bil. &#062; Ayuntamiento de Beneixama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/","og_locale":"ca_ES","og_type":"article","og_title":"Ecoparc m\u00f2bil. &#062; Ayuntamiento de Beneixama","og_url":"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/","og_site_name":"Ayuntamiento de Beneixama","article_modified_time":"2025-09-11T11:18:53+00:00","og_image":[{"width":1252,"height":2560,"url":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/09\/Cartel-General-Horarios-scaled.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/","name":"Ecoparc m\u00f2bil. &#062; Ayuntamiento de Beneixama","isPartOf":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/#primaryimage"},"image":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/#primaryimage"},"thumbnailUrl":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/09\/Cartel-General-Horarios-scaled.png","datePublished":"2019-06-18T07:47:42+00:00","dateModified":"2025-09-11T11:18:53+00:00","breadcrumb":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/#primaryimage","url":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/09\/Cartel-General-Horarios-scaled.png","contentUrl":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/09\/Cartel-General-Horarios-scaled.png","width":1252,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/event\/ecoparc-mobil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/beneixama.diputacionalicante.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/beneixama.diputacionalicante.es\/ca\/events\/"},{"@type":"ListItem","position":3,"name":"Ecoparc m\u00f2bil."}]},{"@type":"WebSite","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#website","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/","name":"Ayuntamiento de Beneixama","description":"Ayuntamiento de Beneixama","publisher":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization"},"alternateName":"Ayuntamiento de Beneixama","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beneixama.diputacionalicante.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#organization","name":"Ayuntamiento de Beneixama","alternateName":"Ayuntamiento de Beneixama","url":"https:\/\/beneixama.diputacionalicante.es\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png","contentUrl":"https:\/\/beneixama.diputacionalicante.es\/wp-content\/uploads\/2025\/05\/login-logo.png","width":350,"height":150,"caption":"Ayuntamiento de Beneixama"},"image":{"@id":"https:\/\/beneixama.diputacionalicante.es\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/tribe_events\/34611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/tribe_events\/34611\/revisions"}],"predecessor-version":[{"id":34612,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/tribe_events\/34611\/revisions\/34612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/media\/33714"}],"wp:attachment":[{"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/media?parent=34611"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/tags?post=34611"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/beneixama.diputacionalicante.es\/ca\/wp-json\/wp\/v2\/tribe_events_cat?post=34611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}